{"id":15140,"date":"2021-11-08T10:40:04","date_gmt":"2021-11-08T10:40:04","guid":{"rendered":"http:\/\/206.189.129.190\/DPT\/payslip_documents\/raju-r-nair-6\/"},"modified":"2021-11-08T10:40:04","modified_gmt":"2021-11-08T10:40:04","slug":"raju-r-nair-6","status":"publish","type":"payslip_documents","link":"https:\/\/www.deendayalport.gov.in\/hi\/payslip_documents\/raju-r-nair-6\/","title":{"rendered":"RAJU R. NAIR"},"content":{"rendered":"","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/www.deendayalport.gov.in\/hi\/wp-json\/wp\/v2\/payslip_documents\/15140"}],"collection":[{"href":"https:\/\/www.deendayalport.gov.in\/hi\/wp-json\/wp\/v2\/payslip_documents"}],"about":[{"href":"https:\/\/www.deendayalport.gov.in\/hi\/wp-json\/wp\/v2\/types\/payslip_documents"}],"wp:attachment":[{"href":"https:\/\/www.deendayalport.gov.in\/hi\/wp-json\/wp\/v2\/media?parent=15140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}