{"id":29713,"date":"2023-08-04T13:18:38","date_gmt":"2023-08-04T07:48:38","guid":{"rendered":"https:\/\/www.deendayalport.gov.in\/?post_type=ledger_documents&#038;p=29713"},"modified":"2023-08-04T13:18:38","modified_gmt":"2023-08-04T07:48:38","slug":"hindustan-petroleum-corpn-ltd-14","status":"publish","type":"ledger_documents","link":"https:\/\/www.deendayalport.gov.in\/hi\/ledger_documents\/hindustan-petroleum-corpn-ltd-14\/","title":{"rendered":"HINDUSTAN PETROLEUM CORPN. LTD."},"template":"","_links":{"self":[{"href":"https:\/\/www.deendayalport.gov.in\/hi\/wp-json\/wp\/v2\/ledger_documents\/29713"}],"collection":[{"href":"https:\/\/www.deendayalport.gov.in\/hi\/wp-json\/wp\/v2\/ledger_documents"}],"about":[{"href":"https:\/\/www.deendayalport.gov.in\/hi\/wp-json\/wp\/v2\/types\/ledger_documents"}],"wp:attachment":[{"href":"https:\/\/www.deendayalport.gov.in\/hi\/wp-json\/wp\/v2\/media?parent=29713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}